{"id":859,"date":"2019-03-18T20:27:16","date_gmt":"2019-03-18T19:27:16","guid":{"rendered":"https:\/\/job-alliance.com\/10-trucs-pour-favoriser-lintegration-dun-travailleur-etranger\/"},"modified":"2019-04-04T23:01:15","modified_gmt":"2019-04-04T21:01:15","slug":"10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero","status":"publish","type":"post","link":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/","title":{"rendered":"10 consejos para ayudar a integrar a un trabajador extranjero."},"content":{"rendered":"<h3>Los empleadores invierten mucho tiempo y energ\u00eda en investigar y contratar candidatos. Sin embargo, muy pocos se est\u00e1n preparando adecuadamente para la llegada de un nuevo miembro a su equipo.<\/h3>\n<p>Seg\u00fan la Orden de los consejeros de recursos humanos autorizados (<a href=\"http:\/\/www.portailrh.org\/expertise\/fiche_reference.aspx?f=19562\" target=\"_blank\" rel=\"noopener noreferrer\">CRHA<\/a>, por sus siglas en franc\u00e9s), el primer contacto del nuevo empleado con su entorno de trabajo f\u00edsico y humano es primordial, sin importar que este sea nacido en Canad\u00e1 o en el extranjero. De hecho, esta persona supedita su relaci\u00f3n con la empresa. Esta primera reuni\u00f3n es una oportunidad para informar al trabajador sobre la historia, los valores, los clientes, los servicios ofrecidos, los miembros del personal y los comportamientos deseados.<\/p>\n<p>En el caso de un trabajador extranjero, este paso es a\u00fan m\u00e1s importante porque la persona tambi\u00e9n debe aclimatarse a un nuevo pa\u00eds y una nueva cultura.<\/p>\n<p>Los expertos en reclutamiento internacional de Job Alliance han identificado <strong>10 comportamientos clave para ayudar a integrar a un trabajador extranjero<\/strong>.<\/p>\n<ol>\n<li>Desarrolle un plan de orientaci\u00f3n que cubra los primeros meses de la entrada del nuevo trabajador. Aseg\u00farese de involucrar a su equipo y escalone las actividades de capacitaci\u00f3n e integraci\u00f3n durante varias semanas para evitar demasiada informaci\u00f3n.<\/li>\n<li>Lo m\u00e1s pronto posible, proporcione la fecha de llegada y la entrada del nuevo empleado.<\/li>\n<li>Para facilitar las primeras conversaciones entre el reci\u00e9n llegado y el equipo existente, es esencial preparar bien a los empleados. No dude en presentar la historia del nuevo colega, sus experiencias profesionales, su familia, su edad, su t\u00edtulo, as\u00ed como informaci\u00f3n sobre su pa\u00eds de origen. Finalmente, comunique claramente a los empleados existentes las razones que llevaron a la contrataci\u00f3n de un trabajador extranjero, para calmar posibles temores.<\/li>\n<li>Facilite el acceso a toda la informaci\u00f3n importante sobre la organizaci\u00f3n y el empleo al reunirlos en una carpeta. Tambi\u00e9n puede imprimir un directorio con fotos y nombres de todo el equipo de trabajo, especificando sus roles y responsabilidades. Como el reci\u00e9n llegado no estar\u00e1 familiarizado con los nombres locales, tendr\u00e1 m\u00e1s facilidad para hablar con un colega en caso de necesidad.<\/li>\n<li>Planifique el programa completo para el primer d\u00eda del nuevo empleado (por ejemplo, de 8:00 a 9:00 de la ma\u00f1ana &#8211; visita de la oficina, de 9:00 a 10:00 de la ma\u00f1ana &#8211; reuni\u00f3n con el supervisor inmediato, de 10:00 a 11:00 de la ma\u00f1ana &#8211; presentaci\u00f3n de las pol\u00edticas y procedimientos de la organizaci\u00f3n, etc.).<\/li>\n<li>Programar una reuni\u00f3n de presentaci\u00f3n formal. Tanto el supervisor inmediato como los empleados clave deben tener un momento individual con el trabajador. Aproveche esta oportunidad para aclarar los deberes, responsabilidades, horario, herramientas, m\u00e9todos de trabajo y otras expectativas, y para validar la comprensi\u00f3n del trabajador. En caso de que a\u00fan no domine el idioma que se habla com\u00fanmente en la empresa, aseg\u00farese de utilizar un vocabulario simple y sin ambig\u00fcedades. El supervisor u otros miembros del equipo deben compartir la hora de comer con el empleado, al menos por unos d\u00edas. Tambi\u00e9n piense en organizar una salida fuera del trabajo para el nuevo empleado, como por ejemplo una cena al restaurante.<\/li>\n<li>Prepare el lugar de trabajo del nuevo empleado con algunos productos locales e incluso invite a sus empleados actuales y al reci\u00e9n llegado a organizar una comida con los sabores de sus respectivos pa\u00edses para que todos puedan descubrir su cultura. \u00bfPorque no?<\/li>\n<li>Aseg\u00farese de reservar un momento al final del d\u00eda para discutir su llegada y hacer una retrospecci\u00f3n. Esta conversaci\u00f3n validar\u00e1 que las tareas correspondan a sus expectativas, que se sienta c\u00f3modo. Invite al nuevo empleado a aclarar cualquier cosa que no le quede clara.<\/li>\n<li>Involucre a sus empleados a trav\u00e9s de programas de mentoring o coaching. Esto ser\u00e1, por un lado, muy gratificante para los empleados existentes, adem\u00e1s de promover, por otro lado, una experiencia positiva para el reci\u00e9n llegado. Algunas empresas incluso implementan guardianes de diversidad, cuya misi\u00f3n es facilitar el proceso de integraci\u00f3n de los reci\u00e9n llegados mediante la intervenci\u00f3n en ciertas situaciones, adem\u00e1s de informarse y establecer las mejores pr\u00e1cticas en t\u00e9rminos de integraci\u00f3n de trabajadores extranjeros.<\/li>\n<li>Tambi\u00e9n es imperativo equipar al supervisor inmediato del reci\u00e9n llegado para que pueda adaptar su modo de administraci\u00f3n de acuerdo con las necesidades \u00fanicas del empleado. Para ayudar a estos gerentes a aceptar los desaf\u00edos futuros, puede involucrarlos en el proceso de contrataci\u00f3n. Tambi\u00e9n los har\u00e1 responsables de la integraci\u00f3n exitosa del reci\u00e9n llegado.<\/li>\n<\/ol>\n<p>En resumen, es importante tener en cuenta que el \u00e9xito de contratar y mantener a un trabajador extranjero depende en gran medida de la calidad de su integraci\u00f3n, tanto en su trabajo como en su entorno. El papel del empleador en este sentido es crucial y pasa por dos ejes principales: la creaci\u00f3n de un entorno inclusivo, as\u00ed como el apoyo y la capacitaci\u00f3n en las empresas. Al poner en su lugar los recursos necesarios, pone todas las posibilidades de su parte para una contrataci\u00f3n exitosa y satisfactoria para todas las partes.<\/p>\n<h3>\u00bfNecesita ayuda para planificar e implementar estas medidas de integraci\u00f3n? \u00a1Podemos ayudarle! \u00a1<a href=\"\/job-alliance?page_id=814\" target=\"_blank\" rel=\"noopener noreferrer\">P\u00f3ngase en contacto con nosotros<\/a>!<\/h3>\n<p>Sources :<\/p>\n<p><a href=\"https:\/\/www.bdc.ca\/fr\/articles-outils\/employes\/recruter\/pages\/integration-nouvel-employe-les-etapes-incontournables.aspx\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.bdc.ca\/fr\/articles-outils\/employes\/recruter\/pages\/integration-nouvel-employe-les-etapes-incontournables.aspx<\/a><\/p>\n<p><a href=\"https:\/\/www.jobboom.com\/carriere\/6-actions-poser-pour-recruter-et-embaucher-les-travailleurs-immigrants\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.jobboom.com\/carriere\/6-actions-poser-pour-recruter-et-embaucher-les-travailleurs-immigrants\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00e9xito de contratar y retener a un trabajador extranjero depende de una variedad de factores, y la integraci\u00f3n del trabajador en su nuevo entorno es fundamental para ello.<\/p>\n","protected":false},"author":1,"featured_media":617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,49],"tags":[],"class_list":["post-859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integracion","category-trabajador-extranjero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 consejos para facilitar la llegada de un trabajador extranjero.<\/title>\n<meta name=\"description\" content=\"Adem\u00e1s de la selecci\u00f3n del candidato adecuado, maximice sus posibilidades de \u00e9xito planeando una bienvenida exitosa. \u00a1Descubra c\u00f3mo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 consejos para facilitar la llegada de un trabajador extranjero.\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s de la selecci\u00f3n del candidato adecuado, maximice sus posibilidades de \u00e9xito planeando una bienvenida exitosa. \u00a1Descubra c\u00f3mo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/\" \/>\n<meta property=\"og:site_name\" content=\"Job Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-18T19:27:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-04T21:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/job-alliance.com\/content\/uploads\/2019\/03\/iStock-586198320.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sudo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sudo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/\",\"url\":\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/\",\"name\":\"10 consejos para facilitar la llegada de un trabajador extranjero.\",\"isPartOf\":{\"@id\":\"https:\/\/job-alliance.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/job-alliance.com\/content\/uploads\/2019\/03\/iStock-586198320.jpg\",\"datePublished\":\"2019-03-18T19:27:16+00:00\",\"dateModified\":\"2019-04-04T21:01:15+00:00\",\"author\":{\"@id\":\"https:\/\/job-alliance.com\/en\/#\/schema\/person\/98f4178ff1dbf10050ff9742741f16c9\"},\"description\":\"Adem\u00e1s de la selecci\u00f3n del candidato adecuado, maximice sus posibilidades de \u00e9xito planeando una bienvenida exitosa. \u00a1Descubra c\u00f3mo!\",\"breadcrumb\":{\"@id\":\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#primaryimage\",\"url\":\"https:\/\/job-alliance.com\/content\/uploads\/2019\/03\/iStock-586198320.jpg\",\"contentUrl\":\"https:\/\/job-alliance.com\/content\/uploads\/2019\/03\/iStock-586198320.jpg\",\"width\":2560,\"height\":1708,\"caption\":\"Group of people working at an embroidery factory and looking at the camera smiling\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.job-alliance.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 consejos para ayudar a integrar a un trabajador extranjero.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/job-alliance.com\/en\/#website\",\"url\":\"https:\/\/job-alliance.com\/en\/\",\"name\":\"Job Alliance\",\"description\":\"Job Alliance \u2013 Services cl\u00e9s en main de recrutement international\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/job-alliance.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/job-alliance.com\/en\/#\/schema\/person\/98f4178ff1dbf10050ff9742741f16c9\",\"name\":\"Sudo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/job-alliance.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9322877e1363c389fde320a341bf57d344a72ac8bff0b32d5ecb6045fa0d6304?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9322877e1363c389fde320a341bf57d344a72ac8bff0b32d5ecb6045fa0d6304?s=96&d=mm&r=g\",\"caption\":\"Sudo\"},\"url\":\"https:\/\/job-alliance.com\/es\/author\/sudo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 consejos para facilitar la llegada de un trabajador extranjero.","description":"Adem\u00e1s de la selecci\u00f3n del candidato adecuado, maximice sus posibilidades de \u00e9xito planeando una bienvenida exitosa. \u00a1Descubra c\u00f3mo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/","og_locale":"es_ES","og_type":"article","og_title":"10 consejos para facilitar la llegada de un trabajador extranjero.","og_description":"Adem\u00e1s de la selecci\u00f3n del candidato adecuado, maximice sus posibilidades de \u00e9xito planeando una bienvenida exitosa. \u00a1Descubra c\u00f3mo!","og_url":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/","og_site_name":"Job Alliance","article_published_time":"2019-03-18T19:27:16+00:00","article_modified_time":"2019-04-04T21:01:15+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/job-alliance.com\/content\/uploads\/2019\/03\/iStock-586198320.jpg","type":"image\/jpeg"}],"author":"Sudo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sudo","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/","url":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/","name":"10 consejos para facilitar la llegada de un trabajador extranjero.","isPartOf":{"@id":"https:\/\/job-alliance.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#primaryimage"},"image":{"@id":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#primaryimage"},"thumbnailUrl":"https:\/\/job-alliance.com\/content\/uploads\/2019\/03\/iStock-586198320.jpg","datePublished":"2019-03-18T19:27:16+00:00","dateModified":"2019-04-04T21:01:15+00:00","author":{"@id":"https:\/\/job-alliance.com\/en\/#\/schema\/person\/98f4178ff1dbf10050ff9742741f16c9"},"description":"Adem\u00e1s de la selecci\u00f3n del candidato adecuado, maximice sus posibilidades de \u00e9xito planeando una bienvenida exitosa. \u00a1Descubra c\u00f3mo!","breadcrumb":{"@id":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#primaryimage","url":"https:\/\/job-alliance.com\/content\/uploads\/2019\/03\/iStock-586198320.jpg","contentUrl":"https:\/\/job-alliance.com\/content\/uploads\/2019\/03\/iStock-586198320.jpg","width":2560,"height":1708,"caption":"Group of people working at an embroidery factory and looking at the camera smiling"},{"@type":"BreadcrumbList","@id":"https:\/\/job-alliance.com\/es\/10-consejos-para-facilitar-la-llegada-de-un-trabajador-extranjero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.job-alliance.com\/es\/"},{"@type":"ListItem","position":2,"name":"10 consejos para ayudar a integrar a un trabajador extranjero."}]},{"@type":"WebSite","@id":"https:\/\/job-alliance.com\/en\/#website","url":"https:\/\/job-alliance.com\/en\/","name":"Job Alliance","description":"Job Alliance \u2013 Services cl\u00e9s en main de recrutement international","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/job-alliance.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/job-alliance.com\/en\/#\/schema\/person\/98f4178ff1dbf10050ff9742741f16c9","name":"Sudo","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/job-alliance.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9322877e1363c389fde320a341bf57d344a72ac8bff0b32d5ecb6045fa0d6304?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9322877e1363c389fde320a341bf57d344a72ac8bff0b32d5ecb6045fa0d6304?s=96&d=mm&r=g","caption":"Sudo"},"url":"https:\/\/job-alliance.com\/es\/author\/sudo\/"}]}},"_links":{"self":[{"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/posts\/859\/"}],"collection":[{"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/comments\/?post=859"}],"version-history":[{"count":3,"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/posts\/859\/revisions\/"}],"predecessor-version":[{"id":862,"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/posts\/859\/revisions\/862\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/media\/617\/"}],"wp:attachment":[{"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/media\/?parent=859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/categories\/?post=859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/job-alliance.com\/es\/wp-json\/wp\/v2\/tags\/?post=859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}